{"id":8,"date":"2019-10-17T21:09:52","date_gmt":"2019-10-17T21:09:52","guid":{"rendered":"http:\/\/www.paternocalabro.it\/wordpress\/?p=8"},"modified":"2019-10-17T21:26:14","modified_gmt":"2019-10-17T21:26:14","slug":"paterno-tra-scrittori-e-ricordi-di-ieri-e-di-oggi","status":"publish","type":"post","link":"https:\/\/www.paternocalabro.it\/wordpress\/tradizioni\/paterno-tra-scrittori-e-ricordi-di-ieri-e-di-oggi\/","title":{"rendered":"Paterno tra scrittori e ricordi di ieri e di oggi"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\"><em>Excursus tra le opere di autori che hanno raccontato la storia del nostro paese <\/em><\/h3>\n\n\n\n<p><em>\u201cUn ricordo \u00e8 come una pietra gettata in un lago; dove cade si disegna nell&#8217;onda di un cerchio; e poi un altro un altro ancora tutti concentrici, insino a che dura la forza dell&#8217;impulso. Nel \u201clago del cuore\u201d avviene lo stesso quando si sveglia un ricordo&#8221;&nbsp;<\/em>(Nicola Misasi).<\/p>\n\n\n\n<p><br>Ed io affermo con forza che si deve sempre ricordare il passato, per vivere bene il presente e per costruire un futuro migliore. E a questo avviene ora anche tra i miei concittadini paternesi, sia tra loro, sia nella \u201cragnatela mondiale\u201d, comunemente chiamata dagli anglofili \u201cWEB\u201d, (World Wide Web), sia con iniziative culturali e sia con manifestazioni di vario genere.<br>Tanti sono i contributi per ricordare ed anch&#8217;io, mi perdonino i miei 25 lettori (Manzoni, scusami se rubo la citazione dai Promessi Sposi), cerco di dare il mio sulla &#8220;rete sociale&#8221; che, al solito, gli anglofili chiamano &#8220;social network&#8221;. Tra i \u201csocial\u201d ricordo, primo fra tutti, il sito&nbsp;<a href=\"http:\/\/www.paternocalabro.it\/\"><strong>www.paternocalabro.it<\/strong><\/a>&nbsp;dell&#8217;amico&nbsp;<strong>Luigi Caputo<\/strong>&nbsp;che tanto lavoro e tanto amore dedica al nostro comune paese di origine e, recentemente,&nbsp;<a href=\"http:\/\/www.paternocalabro.it\/www.facebook.com\/Discovery-Paterno-Calabro\">Discovery Paterno<\/a>.<br><\/p>\n\n\n\n<p>Scrive su Facebook&nbsp;<strong>Franco Michele Greco<\/strong>:&nbsp;<em>&#8220;Il sorgere e il crescere della micro storia alla Duby e alla Le Goff, ha trovato terreno fertile anche a Paterno Calabro (CS) nel recente passato. Per la materia da trattare e per la qualit\u00e0 degli autori, voglio ricordare: P.Michele Stea, P.Francesco Rubino, P. Rocco Benvenuto, Pino Florio S, Luigi Caputo, Maria Lamanna e Franco Gagliardi, Daniela Turco, Catia Martino, (ha rispolverato carte antiche e rare). Preziosi documenti li ha disseppelliti anche il sottoscritto. Ognuno di questi autori, con modestia e passione, ha contribuito, attraverso libri, opuscoli, articoli, al recupero della memoria storica collettiva&#8221;<\/em>.<br>L&#8217;attenzione di Franco Michele Greco alla &#8220;nostra&#8221; terra \u00e8 forte ed antica e lui stesso ha scritto una attenta e pregevole monografia&nbsp;<strong><em>Paterno nella storia nella tradizione<\/em><\/strong>&nbsp;(Edizioni Orizzonti Meridionali, Cosenza 2000).<br><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"677\" src=\"http:\/\/www.paternocalabro.it\/wordpress\/wp-content\/uploads\/2019\/10\/Paternocalabro.it_1965-Paterno_San_Marco_RAI_143-1024x677.jpg\" alt=\"\" class=\"wp-image-9\" srcset=\"https:\/\/www.paternocalabro.it\/wordpress\/wp-content\/uploads\/2019\/10\/Paternocalabro.it_1965-Paterno_San_Marco_RAI_143-1024x677.jpg 1024w, https:\/\/www.paternocalabro.it\/wordpress\/wp-content\/uploads\/2019\/10\/Paternocalabro.it_1965-Paterno_San_Marco_RAI_143-300x198.jpg 300w, https:\/\/www.paternocalabro.it\/wordpress\/wp-content\/uploads\/2019\/10\/Paternocalabro.it_1965-Paterno_San_Marco_RAI_143-768x508.jpg 768w, https:\/\/www.paternocalabro.it\/wordpress\/wp-content\/uploads\/2019\/10\/Paternocalabro.it_1965-Paterno_San_Marco_RAI_143.jpg 1100w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption><em>1965, panorama di San Marco: \u00e8 visibile l&#8217;antenna RAI<\/em><\/figcaption><\/figure>\n\n\n\n<p><strong>Maria Carmela Lamanna<\/strong>\u00a0e\u00a0<strong>Franco Gagliardi<\/strong>, hanno pubblicato\u00a0<strong><em>Paterno Calabro tra passato e presente<\/em><\/strong>\u00a0(Oreste Lucchetta editore, Mendicino 2005). Pi\u00f9 di recente \u00e8 uscito, scritto da\u00a0<strong>Catia Martino<\/strong>, profondamente innamorata della &#8220;ricerca storica&#8221; e di Paterno,\u00a0<strong><em>San Francesco di Paola tra Storia ed archietettura<\/em><\/strong>\u00a0(Incipit Edizioni, Roma 2013).<br>E cito per ultimo, in ordine di tempo,\u00a0<strong>Santocarmine Beltrano<\/strong>\u00a0che ha pubblicato\u00a0<strong><em>Paterno e&#8230; Dai templari al Santo Frate, istantanee di un piccolo grande paese<\/em><\/strong>\u00a0(Gruppo azione locale Savuto, Pianolago 2015). E&#8217; un lavoro &#8220;sui generis&#8221;, in cui l&#8217;atipicit\u00e0 degli argomenti trattati fanno un breve ma denso racconto di montagne, di vecchi sentieri, di sapori di un tempo, di antiche tradizioni, che rievoca il paese calpestato al suo passaggio dai regali calzari dell&#8217;imperatore\u00a0<strong>Carlo V<\/strong>, sul cui regno non tramontava mai il sole, nel ritorno vittorioso dall\u2019Africa, nel 1535, proveniente da Rogliano, percorso nella direttrice che dalla Calabria centro-occidentale portava a Roma, dove Carlo voleva incontrare il Papa per farselo alleato, che ricorda che a Paterno oper\u00f2 e visse a lungo\u00a0<em>u poveru fraticellu &#8216;e Paula<\/em>.<br>La narrazione di Paterno parte sin dai tempi remoti e dal lavoro di Beltrano apprendiamo che: <\/p>\n\n\n\n<ul><li>nel territorio di Paterno preesisteva un insediamento romano, passaggio obbligato tra Capua e Reggio Calabria, attraverso la &#8220;Via Popilia&#8221;, che costeggiava il torrente &#8220;Jassa&#8221;; <\/li><li>Paterno nacque dopo le invasioni saracene ad opera dei cosentini che cercavano luoghi per difendersi; <\/li><li>in passato &#8211; e lo ricordo ancora ragazzo negli anni &#8217;50 &#8211; si allevava il baco da seta, e si coltivava il lino, e abili artigiane tessevano corredi per le ricche famiglie di Cosenza; <\/li><li>il &#8220;Capitolo diocesano&#8221; di Cosenza imped\u00ec, nel 1200, la fondazione di un&#8217;abbazia florense, mentre nel 1444 si realizza la costruzione del Convento di San Francesco; <\/li><li>la Chiesa di San Giovanni, 1200, testimonia il passaggio dei templari;<\/li><li>che Carlo V nel XVI secolo pass\u00f2 da Paterno e concesse privilegi, quali tenere fiere pi\u00f9 volte all&#8217;anno, per ringraziare dell&#8217;accoglienza; <\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"http:\/\/www.paternocalabro.it\/wordpress\/wp-content\/uploads\/2019\/10\/Paternocalabro.it_1995-Paterno_Santuario_SanFrancescoDiPaola_289-1024x768.jpg\" alt=\"\" class=\"wp-image-13\" srcset=\"https:\/\/www.paternocalabro.it\/wordpress\/wp-content\/uploads\/2019\/10\/Paternocalabro.it_1995-Paterno_Santuario_SanFrancescoDiPaola_289-1024x768.jpg 1024w, https:\/\/www.paternocalabro.it\/wordpress\/wp-content\/uploads\/2019\/10\/Paternocalabro.it_1995-Paterno_Santuario_SanFrancescoDiPaola_289-300x225.jpg 300w, https:\/\/www.paternocalabro.it\/wordpress\/wp-content\/uploads\/2019\/10\/Paternocalabro.it_1995-Paterno_Santuario_SanFrancescoDiPaola_289-768x576.jpg 768w, https:\/\/www.paternocalabro.it\/wordpress\/wp-content\/uploads\/2019\/10\/Paternocalabro.it_1995-Paterno_Santuario_SanFrancescoDiPaola_289.jpg 1632w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption> <em>1995, l&#8217;ingresso del Santuario di Francesco. <\/em><\/figcaption><\/figure>\n\n\n\n<p>Grande spazio, infine, \u00e8 dedicato alle tante chiese, ahim\u00e8 spesso in rovina, e a palazzi notevoli. Affermo che il motivo pi\u00f9 notevole per ricordare e visitare Paterno \u00e8 il Santuario Convento di San Francesco di Paola. Palazzi, chiese spesso sono in rovina, purtroppo, ma il Santuario, a dimostrazione del miracolo perenne del Taumaturgo, \u00e8 in buone condizioni e ben tenuto, anche se rispetto a mezzo secolo fa i frati minimi sono pochi. Senza il Santuario Paterno sarebbe un minuscolo puntino sulla carta geografica!<br>Tra le pubblicazioni che in vario modo trattano di Paterno ricordiamo:<\/p>\n\n\n\n<ul><li><\/li><\/ul>\n\n\n\n<ol><li><strong>Francesco Arnoni<\/strong>, <em>La Calabria illustrata, vol. IV, Il circondario di Cosenza, 1874, ristampa Edizioni Orizzonti Meridionali, Cosenza 1995<\/em>. A Paterno l&#8217;Arnoni dedica le pagine 148 e 149 ricordandone personaggi quali, tra gli altri; Pietro Caputi, monaco agostiniano, teologo (1350); il beato Paolo Rendace, compagno di San Francesco, che mor\u00ec nel 1521; Apollonio Merenda, cappellano del cardinale Polo a Roma, fatto &#8220;morire di morte lenta&#8221;, alla fine del XVI secolo, per sentenza dell&#8217;Inquisizione, quando si scopr\u00ec essere calvinista. Arnoni fa una notazione curiosa e triste: Paterno \u00e8 detto il paese delle monache di casa; di vero due terzi, a dir poco, delle donne di questo villaggio, spinte o sponte, son monache senza voto nessuno. Da qui origina nel paese un treno di scandali, e di non pi\u00f9 udite immoralit\u00e0 (Opera citata). La medesima definizione l&#8217;Arnoni ripete per Scigliano che al pari di Paterno Calabro, \u00e8 la patria delle monache di casa (opera citata, pag. 244). <\/li><li><strong>P. Michele Stea<\/strong>, <em>Il santuario di Paterno Calabro, monografia storica, Chiappetta editore, Cosenza 1970<\/em>, con informazioni utili per visitare il santuario e il paese. <\/li><li><em>A cura di <\/em><strong>Depinius<\/strong><em>, Paterno Calabro itinerari culturali con brevi cenni storici, Santuario, Chiese, tradizioni. (Edizioni Santelli, Mendicino 1993)<\/em>, con storia, arte, santuario, tradizioni e molte foto. <\/li><li><strong>P. Francesco Rubino,<\/strong> <em>San Francesco di Paola a Paterno, il suo santuario, P: Paolo Rendace, (Paterno 2004)<\/em>, dedicato a Lauretta e Pietro Ettore, amatissimi genitori di p. Francesco recentemente scomparso. Conservo con amore questo libro con una dedica personale a me fatta dall&#8217;autore. Nel testo, leggiamo il rapporto del Santo con Paterno, l&#8217;apostolato di pace, la &#8220;fontana&#8221;, l&#8217;architrave spezzato, la peste scampata, il chiostro, la grotta, i buoi &#8220;messaggeri&#8221;, la partenza per la Francia, p. Paolo Rendace.<\/li><\/ol>\n\n\n\nPer le pagine dedicate a Paterno voglio ricordare:\nNicola Misasi, La mente e il cuore di Francesco di Paola, R. Carabba editore, Lanciano 1907, ristampato per Cultura calabrese editrice, Belvedere 1981, senza le storiche foto dell&#8217;opera originale. Si ha una edizione in lingua inglese, &#8220;The mint and heart of Francis of Paula, traslated into english by Tarquinio Valese\u201d, edizioni Lubrano, Napoli 1911. Nell&#8217;edizione originale Misasi dedica a Paterno, suo paese natio, l&#8217;incipit del capitolo iniziale Francesco nella tradizione e nel sentimento calabrese: vi si narra di un paternese, che, recatosi a Roma per incontrare un deputato, troppo occupato per riceverlo, in visita a San Pietro allo scorgere della statua del Santo a lui familiare ritrova la serenit\u00e0 che lo &#8220;smarrimento&#8221; della grande citt\u00e0 gli aveva fatto perdere. E poi le pagine sulla fondazione del convento di Paterno: E Francesco accett\u00f2 l&#8217;invito dei cittadini di Paterno sol perch\u00e9, a parer mio, pi\u00f9 che altrove, in quel paesello montano il convento avrebbe potuto riuscire utile alle molte borgate vicine di cui Paterno \u00e8 centro.\nE poi &#8230;. \u201cQuante, quante volte, fanciulletto ancora, seduto sul rustico sedile innanzi al convento&#8230;. meditando sull&#8217;uomo singolare, la cui grande anima sentivo in tutte le cose &#8230; mi pareva di vederne la bella, dolce e pur gagliarda figura\u201d.\np. Giuseppe Maria Roberti, San Francesco di Paola, storia della sua vita. (Edizioni f.lli Tempesta, Roma 1915), dono (4 aprile 1928) del p. Giuseppe Cristiani, correttore dell&#8217;ordine dei PP. MM. nel santuario di Paterno, a mio padre Elia, allora ventitreenne. Le prime pagine riportano notizie bibliografiche sul Santo, che abbracciano gli anni dal secolo XV al 1915 del secolo XX. P. Roberto cita Nicola Misasi (vedi sopra), stroncandone l&#8217;opera su san Francesco, descritto da un laico ed infine un elenco di opere storiche sul santo, scritti del santo. A Paterno sono dedicati i capitoli XI (\u201cFondazione del convento nel 1444\u201d) e XII (\u201cApostolato di pacificazione e vita di Francesco a Paterno dal 1444 al 1453\u201d), pagine 184-216.\nClaudia Misasi, Nicola Misasi tra le righe &#8211; Una vita, tante storie, Brenner Editore, Cosenza 2007. La discendente del cantore della Sila e della Calabria, attraverso gli scritti di Nicola Misasi, ne rievoca i momenti dell&#8217;infanzia, vissuta a Paterno. Per San Francesco lo scrittore sente &#8220;una profonda tenerezza, perocch\u00e8 i miei sono di Paterno, il paesello ove egli &#8211; il santo &#8211; visse tanto della sua vita di amore e di carit\u00e0&#8221;.\n","protected":false},"excerpt":{"rendered":"<p>Excursus tra le opere di autori che hanno raccontato la storia del nostro paese \u201cUn<\/p>\n","protected":false},"author":1,"featured_media":17,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"_links":{"self":[{"href":"https:\/\/www.paternocalabro.it\/wordpress\/wp-json\/wp\/v2\/posts\/8"}],"collection":[{"href":"https:\/\/www.paternocalabro.it\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.paternocalabro.it\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.paternocalabro.it\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paternocalabro.it\/wordpress\/wp-json\/wp\/v2\/comments?post=8"}],"version-history":[{"count":4,"href":"https:\/\/www.paternocalabro.it\/wordpress\/wp-json\/wp\/v2\/posts\/8\/revisions"}],"predecessor-version":[{"id":16,"href":"https:\/\/www.paternocalabro.it\/wordpress\/wp-json\/wp\/v2\/posts\/8\/revisions\/16"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.paternocalabro.it\/wordpress\/wp-json\/wp\/v2\/media\/17"}],"wp:attachment":[{"href":"https:\/\/www.paternocalabro.it\/wordpress\/wp-json\/wp\/v2\/media?parent=8"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.paternocalabro.it\/wordpress\/wp-json\/wp\/v2\/categories?post=8"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.paternocalabro.it\/wordpress\/wp-json\/wp\/v2\/tags?post=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}